{"id":233590,"date":"2026-02-22T17:45:41","date_gmt":"2026-02-22T16:45:41","guid":{"rendered":"https:\/\/schneiter-storen.ch\/ersatzteile\/?post_type=product&#038;p=233590"},"modified":"2026-02-22T18:30:36","modified_gmt":"2026-02-22T17:30:36","slug":"sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis","status":"publish","type":"product","link":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/","title":{"rendered":"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Sonnenstore Typ Stobag AZUR SG2400<\/strong><\/p>\n<p>Stabile, kompakte und vielseitig einsetzbare 4-kant Tragrohrmarkise<\/p>\n<p><strong>Technische Daten:<\/strong><\/p>\n<p>Breite: 4960 mm<\/p>\n<p>Ausladung: 3000 mm<\/p>\n<p>Antrieb: Getriebe und Kurbel rechts von Aussen gesehen<\/p>\n<p>Gestellfarbe: RAL 9016 Traffic White<\/p>\n<p>Volant: Ohne Volant<\/p>\n<p>Montage: Wand oder Deckenmontage<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lieferung?<\/strong><\/p>\n<p>Eine Lieferung zu Ihrem Wunschort ist gegen Aufpreis m\u00f6glich.<\/p>\n<p><strong>Montage?<\/strong><\/p>\n<p>Die Montage durch unser Team ist gegen Aufpreis m\u00f6glich.<\/p>\n<p><strong>Produkte-Flyer siehe untenstehender Link:<\/strong><\/p>\n<p><a href=\"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/Azur.pdf\">Azur<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Sonnenstore Typ Stobag AZUR SG2400 Stabile, kompakte und vielseitig einsetzbare 4-kant Tragrohrmarkise Technische Daten: Breite: 4960 mm Ausladung: 3000 mm Antrieb: Getriebe und Kurbel rechts von Aussen gesehen Gestellfarbe: RAL 9016 Traffic White Volant: Ohne Volant Montage: Wand oder Deckenmontage &nbsp; Lieferung? Eine Lieferung zu Ihrem Wunschort ist gegen Aufpreis m\u00f6glich. Montage? Die Montage [&hellip;]<\/p>\n","protected":false},"featured_media":233576,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":["post-233590","product","type-product","status-publish","has-post-thumbnail","product_cat-unkategorisiert","product_shipping_class-abholung-vor-ort-in-grosshoechstetten","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Sonnenstore Typ Stobag AZUR SG2400 Stabile, kompakte und vielseitig einsetzbare 4-kant Tragrohrmarkise Technische Daten: Breite: 4960 mm Ausladung: 3000 mm Antrieb: Getriebe und Kurbel rechts von Aussen gesehen Gestellfarbe: RAL 9016 Traffic White Volant: Ohne Volant Montage: Wand oder Deckenmontage &nbsp; Lieferung? Eine Lieferung zu Ihrem Wunschort ist gegen Aufpreis m\u00f6glich. Montage? Die Montage [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/\" \/>\n<meta property=\"og:site_name\" content=\"Schneiter Storen AG Ersatzteilshop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schneiter-Storen-AG-102972985016682\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T17:30:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/IMG_0398-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2880\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/\",\"url\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/\",\"name\":\"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/wp-content\\\/uploads\\\/IMG_0398-scaled.jpeg\",\"datePublished\":\"2026-02-22T16:45:41+00:00\",\"dateModified\":\"2026-02-22T17:30:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/wp-content\\\/uploads\\\/IMG_0398-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/wp-content\\\/uploads\\\/IMG_0398-scaled.jpeg\",\"width\":2880,\"height\":2160,\"caption\":\"IMG 0398\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/produkt\\\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#website\",\"url\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/\",\"name\":\"Schneiter Storen AG Ersatzteilshop\",\"description\":\"Sonne ist geil - Schatten ist cool!\",\"publisher\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#organization\",\"name\":\"Schneiter-Storen\",\"url\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/wp-content\\\/uploads\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/wp-content\\\/uploads\\\/logo.png\",\"width\":500,\"height\":188,\"caption\":\"Schneiter-Storen\"},\"image\":{\"@id\":\"https:\\\/\\\/schneiter-storen.ch\\\/ersatzteile\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schneiter-Storen-AG-102972985016682\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/schneiter-storen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/","og_locale":"de_DE","og_type":"article","og_title":"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop","og_description":"&nbsp; Sonnenstore Typ Stobag AZUR SG2400 Stabile, kompakte und vielseitig einsetzbare 4-kant Tragrohrmarkise Technische Daten: Breite: 4960 mm Ausladung: 3000 mm Antrieb: Getriebe und Kurbel rechts von Aussen gesehen Gestellfarbe: RAL 9016 Traffic White Volant: Ohne Volant Montage: Wand oder Deckenmontage &nbsp; Lieferung? Eine Lieferung zu Ihrem Wunschort ist gegen Aufpreis m\u00f6glich. Montage? Die Montage [&hellip;]","og_url":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/","og_site_name":"Schneiter Storen AG Ersatzteilshop","article_publisher":"https:\/\/www.facebook.com\/Schneiter-Storen-AG-102972985016682","article_modified_time":"2026-02-22T17:30:36+00:00","og_image":[{"width":2880,"height":2160,"url":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/IMG_0398-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/","url":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/","name":"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis) - Schneiter Storen AG Ersatzteilshop","isPartOf":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/#primaryimage"},"image":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/#primaryimage"},"thumbnailUrl":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/IMG_0398-scaled.jpeg","datePublished":"2026-02-22T16:45:41+00:00","dateModified":"2026-02-22T17:30:36+00:00","breadcrumb":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/#primaryimage","url":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/IMG_0398-scaled.jpeg","contentUrl":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/IMG_0398-scaled.jpeg","width":2880,"height":2160,"caption":"IMG 0398"},{"@type":"BreadcrumbList","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/produkt\/sonnenstore-ab-lager-breite-496cm-x-ausladung-300cm-40-vom-neupreis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/schneiter-storen.ch\/ersatzteile\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/schneiter-storen.ch\/ersatzteile\/"},{"@type":"ListItem","position":3,"name":"Sonnenstore ab Lager Breite 496cm x Ausladung 300cm (- 40% vom Neupreis)"}]},{"@type":"WebSite","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#website","url":"https:\/\/schneiter-storen.ch\/ersatzteile\/","name":"Schneiter Storen AG Ersatzteilshop","description":"Sonne ist geil - Schatten ist cool!","publisher":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schneiter-storen.ch\/ersatzteile\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#organization","name":"Schneiter-Storen","url":"https:\/\/schneiter-storen.ch\/ersatzteile\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#\/schema\/logo\/image\/","url":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/logo.png","contentUrl":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-content\/uploads\/logo.png","width":500,"height":188,"caption":"Schneiter-Storen"},"image":{"@id":"https:\/\/schneiter-storen.ch\/ersatzteile\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schneiter-Storen-AG-102972985016682","https:\/\/www.linkedin.com\/company\/schneiter-storen\/"]}]}},"_links":{"self":[{"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/product\/233590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/comments?post=233590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/media\/233576"}],"wp:attachment":[{"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/media?parent=233590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/product_brand?post=233590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/product_cat?post=233590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schneiter-storen.ch\/ersatzteile\/wp-json\/wp\/v2\/product_tag?post=233590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}